{"id":3942,"date":"2024-08-16T02:21:15","date_gmt":"2024-08-16T02:21:15","guid":{"rendered":"https:\/\/ecofinishcoatings.com\/calendrier-du-salon\/"},"modified":"2025-10-21T14:45:03","modified_gmt":"2025-10-21T14:45:03","slug":"calendrier-du-salon","status":"publish","type":"page","link":"https:\/\/ecofinishcoatings.com\/fr\/calendrier-du-salon\/","title":{"rendered":"Calendrier du salon"},"content":{"rendered":"<div id=\"cs-content\" class=\"cs-content\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Prochains salons Aucun \u00e9v\u00e9nement trouv\u00e9 !<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-blank-4.php","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-3942","page","type-page","status-publish","hentry","no-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calendrier du salon - Rev\u00eatements ecoFINISH<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez o\u00f9 rencontrer l\u2019\u00e9quipe ecoFINISH lors des prochains salons professionnels. Consultez notre calendrier des \u00e9v\u00e9nements et retrouvez-nous pour des d\u00e9monstrations et conseils d\u2019experts.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecofinishcoatings.com\/fr\/calendrier-du-salon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calendrier du salon - Rev\u00eatements ecoFINISH\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez o\u00f9 rencontrer l\u2019\u00e9quipe ecoFINISH lors des prochains salons professionnels. Consultez notre calendrier des \u00e9v\u00e9nements et retrouvez-nous pour des d\u00e9monstrations et conseils d\u2019experts.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecofinishcoatings.com\/fr\/calendrier-du-salon\/\" \/>\n<meta property=\"og:site_name\" content=\"ecoFINISH Coatings\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-21T14:45:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecofinishcoatings.com\\\/fr\\\/calendrier-du-salon\\\/\",\"url\":\"https:\\\/\\\/ecofinishcoatings.com\\\/fr\\\/calendrier-du-salon\\\/\",\"name\":\"Calendrier du salon - Rev\u00eatements ecoFINISH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecofinishcoatings.com\\\/fr\\\/#website\"},\"datePublished\":\"2024-08-16T02:21:15+00:00\",\"dateModified\":\"2025-10-21T14:45:03+00:00\",\"description\":\"D\u00e9couvrez o\u00f9 rencontrer l\u2019\u00e9quipe ecoFINISH lors des prochains salons professionnels. Consultez notre calendrier des \u00e9v\u00e9nements et retrouvez-nous pour des d\u00e9monstrations et conseils d\u2019experts.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecofinishcoatings.com\\\/fr\\\/calendrier-du-salon\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ecofinishcoatings.com\\\/fr\\\/calendrier-du-salon\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecofinishcoatings.com\\\/fr\\\/calendrier-du-salon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecofinishcoatings.com\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calendrier du salon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecofinishcoatings.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ecofinishcoatings.com\\\/fr\\\/\",\"name\":\"ecoFINISH Coatings\",\"description\":\"a new era of coatings\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecofinishcoatings.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calendrier du salon - Rev\u00eatements ecoFINISH","description":"D\u00e9couvrez o\u00f9 rencontrer l\u2019\u00e9quipe ecoFINISH lors des prochains salons professionnels. Consultez notre calendrier des \u00e9v\u00e9nements et retrouvez-nous pour des d\u00e9monstrations et conseils d\u2019experts.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecofinishcoatings.com\/fr\/calendrier-du-salon\/","og_locale":"fr_FR","og_type":"article","og_title":"Calendrier du salon - Rev\u00eatements ecoFINISH","og_description":"D\u00e9couvrez o\u00f9 rencontrer l\u2019\u00e9quipe ecoFINISH lors des prochains salons professionnels. Consultez notre calendrier des \u00e9v\u00e9nements et retrouvez-nous pour des d\u00e9monstrations et conseils d\u2019experts.","og_url":"https:\/\/ecofinishcoatings.com\/fr\/calendrier-du-salon\/","og_site_name":"ecoFINISH Coatings","article_modified_time":"2025-10-21T14:45:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecofinishcoatings.com\/fr\/calendrier-du-salon\/","url":"https:\/\/ecofinishcoatings.com\/fr\/calendrier-du-salon\/","name":"Calendrier du salon - Rev\u00eatements ecoFINISH","isPartOf":{"@id":"https:\/\/ecofinishcoatings.com\/fr\/#website"},"datePublished":"2024-08-16T02:21:15+00:00","dateModified":"2025-10-21T14:45:03+00:00","description":"D\u00e9couvrez o\u00f9 rencontrer l\u2019\u00e9quipe ecoFINISH lors des prochains salons professionnels. Consultez notre calendrier des \u00e9v\u00e9nements et retrouvez-nous pour des d\u00e9monstrations et conseils d\u2019experts.","breadcrumb":{"@id":"https:\/\/ecofinishcoatings.com\/fr\/calendrier-du-salon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecofinishcoatings.com\/fr\/calendrier-du-salon\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ecofinishcoatings.com\/fr\/calendrier-du-salon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecofinishcoatings.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Calendrier du salon"}]},{"@type":"WebSite","@id":"https:\/\/ecofinishcoatings.com\/fr\/#website","url":"https:\/\/ecofinishcoatings.com\/fr\/","name":"ecoFINISH Coatings","description":"a new era of coatings","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecofinishcoatings.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/ecofinishcoatings.com\/fr\/wp-json\/wp\/v2\/pages\/3942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecofinishcoatings.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ecofinishcoatings.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ecofinishcoatings.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ecofinishcoatings.com\/fr\/wp-json\/wp\/v2\/comments?post=3942"}],"version-history":[{"count":0,"href":"https:\/\/ecofinishcoatings.com\/fr\/wp-json\/wp\/v2\/pages\/3942\/revisions"}],"wp:attachment":[{"href":"https:\/\/ecofinishcoatings.com\/fr\/wp-json\/wp\/v2\/media?parent=3942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}