{"id":4434,"date":"2024-08-16T02:21:15","date_gmt":"2024-08-16T02:21:15","guid":{"rendered":"https:\/\/ecofinishcoatings.com\/programa-de-la-feria\/"},"modified":"2025-11-03T15:48:21","modified_gmt":"2025-11-03T15:48:21","slug":"programa-de-la-feria","status":"publish","type":"page","link":"https:\/\/ecofinishcoatings.com\/es\/programa-de-la-feria\/","title":{"rendered":"Programa de la Feria"},"content":{"rendered":"<div id=\"cs-content\" class=\"cs-content\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00f3ximas ferias \u00a1No hay eventos!<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-blank-4.php","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-4434","page","type-page","status-publish","hentry","no-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Porgrama de la Feria - Recubrimientos ecoFINISH<\/title>\n<meta name=\"description\" content=\"Descubra d\u00f3nde encontrar al equipo de ecoFINISH\u00ae. Consulte las pr\u00f3ximas ferias y eventos para conocer nuestros revestimientos de alto rendimiento para piscinas y superficies.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecofinishcoatings.com\/es\/programa-de-la-feria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Porgrama de la Feria - Recubrimientos ecoFINISH\" \/>\n<meta property=\"og:description\" content=\"Descubra d\u00f3nde encontrar al equipo de ecoFINISH\u00ae. Consulte las pr\u00f3ximas ferias y eventos para conocer nuestros revestimientos de alto rendimiento para piscinas y superficies.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecofinishcoatings.com\/es\/programa-de-la-feria\/\" \/>\n<meta property=\"og:site_name\" content=\"ecoFINISH Coatings\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-03T15:48:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecofinishcoatings.com\\\/es\\\/programa-de-la-feria\\\/\",\"url\":\"https:\\\/\\\/ecofinishcoatings.com\\\/es\\\/programa-de-la-feria\\\/\",\"name\":\"Porgrama de la Feria - Recubrimientos ecoFINISH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecofinishcoatings.com\\\/es\\\/#website\"},\"datePublished\":\"2024-08-16T02:21:15+00:00\",\"dateModified\":\"2025-11-03T15:48:21+00:00\",\"description\":\"Descubra d\u00f3nde encontrar al equipo de ecoFINISH\u00ae. Consulte las pr\u00f3ximas ferias y eventos para conocer nuestros revestimientos de alto rendimiento para piscinas y superficies.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecofinishcoatings.com\\\/es\\\/programa-de-la-feria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ecofinishcoatings.com\\\/es\\\/programa-de-la-feria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecofinishcoatings.com\\\/es\\\/programa-de-la-feria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecofinishcoatings.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programa de la Feria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecofinishcoatings.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ecofinishcoatings.com\\\/es\\\/\",\"name\":\"ecoFINISH Coatings\",\"description\":\"a new era of coatings\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecofinishcoatings.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Porgrama de la Feria - Recubrimientos ecoFINISH","description":"Descubra d\u00f3nde encontrar al equipo de ecoFINISH\u00ae. Consulte las pr\u00f3ximas ferias y eventos para conocer nuestros revestimientos de alto rendimiento para piscinas y superficies.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecofinishcoatings.com\/es\/programa-de-la-feria\/","og_locale":"es_ES","og_type":"article","og_title":"Porgrama de la Feria - Recubrimientos ecoFINISH","og_description":"Descubra d\u00f3nde encontrar al equipo de ecoFINISH\u00ae. Consulte las pr\u00f3ximas ferias y eventos para conocer nuestros revestimientos de alto rendimiento para piscinas y superficies.","og_url":"https:\/\/ecofinishcoatings.com\/es\/programa-de-la-feria\/","og_site_name":"ecoFINISH Coatings","article_modified_time":"2025-11-03T15:48:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecofinishcoatings.com\/es\/programa-de-la-feria\/","url":"https:\/\/ecofinishcoatings.com\/es\/programa-de-la-feria\/","name":"Porgrama de la Feria - Recubrimientos ecoFINISH","isPartOf":{"@id":"https:\/\/ecofinishcoatings.com\/es\/#website"},"datePublished":"2024-08-16T02:21:15+00:00","dateModified":"2025-11-03T15:48:21+00:00","description":"Descubra d\u00f3nde encontrar al equipo de ecoFINISH\u00ae. Consulte las pr\u00f3ximas ferias y eventos para conocer nuestros revestimientos de alto rendimiento para piscinas y superficies.","breadcrumb":{"@id":"https:\/\/ecofinishcoatings.com\/es\/programa-de-la-feria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecofinishcoatings.com\/es\/programa-de-la-feria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ecofinishcoatings.com\/es\/programa-de-la-feria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecofinishcoatings.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Programa de la Feria"}]},{"@type":"WebSite","@id":"https:\/\/ecofinishcoatings.com\/es\/#website","url":"https:\/\/ecofinishcoatings.com\/es\/","name":"ecoFINISH Coatings","description":"a new era of coatings","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecofinishcoatings.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/ecofinishcoatings.com\/es\/wp-json\/wp\/v2\/pages\/4434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecofinishcoatings.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ecofinishcoatings.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ecofinishcoatings.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ecofinishcoatings.com\/es\/wp-json\/wp\/v2\/comments?post=4434"}],"version-history":[{"count":0,"href":"https:\/\/ecofinishcoatings.com\/es\/wp-json\/wp\/v2\/pages\/4434\/revisions"}],"wp:attachment":[{"href":"https:\/\/ecofinishcoatings.com\/es\/wp-json\/wp\/v2\/media?parent=4434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}